{"id":765,"count":4,"description":"","link":"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/","name":"zafra langostino","slug":"zafra-langostino","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/tag\\\/zafra-langostino\\\/#listItem\",\"name\":\"zafra langostino\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/tag\\\/zafra-langostino\\\/#listItem\",\"position\":2,\"name\":\"zafra langostino\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/#collectionpage\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/\",\"name\":\"zafra langostino - Parte de pesca\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logoparte.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/#organizationLogo\",\"width\":654,\"height\":402},\"image\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/765\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"zafra langostino - Parte de pesca","description":"","canonical_url":"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","position":1,"name":"Home","item":"https:\/\/partedepesca.com.ar\/d","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/#listItem","name":"zafra langostino"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/#listItem","position":2,"name":"zafra langostino","previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/#collectionpage","url":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/","name":"zafra langostino - Parte de pesca","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/#website"},"breadcrumb":{"@id":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/partedepesca.com.ar\/d\/#organization","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","url":"https:\/\/partedepesca.com.ar\/d\/","logo":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/03\/logoparte.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/#organizationLogo","width":654,"height":402},"image":{"@id":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/partedepesca.com.ar\/d\/#website","url":"https:\/\/partedepesca.com.ar\/d\/","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","inLanguage":"es-AR","publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tzafra langostino\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/partedepesca.com.ar\/d"},{"label":"zafra langostino","link":"https:\/\/partedepesca.com.ar\/d\/tag\/zafra-langostino\/"}],"_links":{"self":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags\/765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts?tags=765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}