{"id":7607,"date":"2024-07-02T00:33:23","date_gmt":"2024-07-02T00:33:23","guid":{"rendered":"https:\/\/partedepesca.com.ar\/d\/?p=7607"},"modified":"2024-07-03T15:56:48","modified_gmt":"2024-07-03T15:56:48","slug":"flota-espanola-prepara-zarpada-para-ir-a-pescar-a-malvinas","status":"publish","type":"post","link":"https:\/\/partedepesca.com.ar\/d\/flota-espanola-prepara-zarpada-para-ir-a-pescar-a-malvinas\/","title":{"rendered":"Flota espa\u00f1ola prepara zarpada para ir a pescar a Malvinas"},"content":{"rendered":"\n<p>Ultiman preparativos en el puerto de Vigo unos diecis\u00e9is buques que gozan de licencias de pesca otorgadas por el ileg\u00edtimo Gobierno que usurpa el territorio argentino.<\/p>\n\n\n\n<p>Son embarcaciones de la flota mixta brit\u00e1nica y espa\u00f1ola, que en los pr\u00f3ximos d\u00edas comenzar\u00e1n su traves\u00eda desde Europa hacia el Atl\u00e1ntico Sur con el fin de explotar los recursos pesqueros de las Islas Malvinas.<\/p>\n\n\n\n<p>Luego de una exitosa primera temporada con 60 mil toneladas de calamar de captura, los 16 pesqueros congeladores que tienen base en los puertos espa\u00f1oles, hacen preparativos log\u00edsticos y de abastecimiento para volver a Malvinas y encarar la segunda temporada anual de captura del calamar loligo dentro del mar argentino, pero con autorizaci\u00f3n inglesa. Flota, cuyo producido tiene a Espa\u00f1a y la Uni\u00f3n Europea, como los principales clientes.<\/p>\n\n\n\n<p>El traslado de los buques a la regi\u00f3n usurpada por el Reino Unido dura 15 d\u00edas. La temporada de pesca inicia en un mes, y esperan capturar al menos 35.000 toneladas del calamar patag\u00f3nico o loligo.<\/p>\n\n\n\n<p>Desde la Cooperativa de Armadores de Pesca del Puerto de Vigo (ARVI), Javier Touza, sostuvo que \u201csomos optimistas, all\u00ed estaremos los 16 barcos de las sociedades mixtas\u201d.<\/p>\n\n\n\n<p>El diario Atl\u00e1ntico de Vigo se\u00f1ala que \u201cel acuerdo con el Gobierno de Falkland se alarga todav\u00eda por 20 a\u00f1os, lo que ha permitido construir nuevos congeladores para dar el relevo a algunos de los m\u00e1s veteranos\u201d.<\/p>\n\n\n\n<p>Entre febrero y abril de este a\u00f1o, una flota de 105 buques de bandera espa\u00f1ola, taiwanesa y surcoreana pescaron 142.680 toneladas de calamar en la primera temporada.<\/p>\n\n\n\n<p>Esa flota la componen 88 barcos poteros de taiwaneses y surcoreanos y otros 17 arrastreros congeladores de Espa\u00f1a que usufrutuan las licencias que les concede el ileg\u00edtimo Gobierno del Reino Unido en Malvinas. Casi 60 mil toneladas fueron faenadas por los buques con base en Vigo y las restantes la flota asi\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultiman preparativos en el puerto de Vigo unos diecis\u00e9is buques que gozan de licencias de pesca otorgadas por el ileg\u00edtimo Gobierno que usurpa el territorio argentino. Son embarcaciones de la flota mixta brit\u00e1nica y espa\u00f1ola, que en los pr\u00f3ximos d\u00edas comenzar\u00e1n su traves\u00eda desde Europa hacia el Atl\u00e1ntico Sur con el fin de explotar los<\/p>\n","protected":false},"author":4,"featured_media":7608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[963,91,1398,1400,838,1397,1399],"class_list":{"0":"post-7607","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-calamar-loligo","9":"tag-featured","10":"tag-flota-espanola","11":"tag-gobierno-ilegitimo-de-malvinas","12":"tag-islas-malvinas","13":"tag-pesca-malvinas","14":"tag-puerto-de-vigo"},"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/7607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/comments?post=7607"}],"version-history":[{"count":2,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/7607\/revisions"}],"predecessor-version":[{"id":7610,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/7607\/revisions\/7610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media\/7608"}],"wp:attachment":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media?parent=7607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/categories?post=7607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags?post=7607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}