{"id":2503,"date":"2023-06-01T18:41:44","date_gmt":"2023-06-01T18:41:44","guid":{"rendered":"https:\/\/partedepesca.com.ar\/d\/?p=2503"},"modified":"2023-06-05T16:01:25","modified_gmt":"2023-06-05T16:01:25","slug":"santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari","status":"publish","type":"post","link":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/","title":{"rendered":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de Caleta Olivia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La desposesi\u00f3n de los bienes a la empresa privada por parte del Estado provincial ocurri\u00f3 en diciembre de 2009, durante el gobierno de Daniel Peralta, y se inici\u00f3 un extenso proceso judicial en torno a la discrepancia en cuanto al importe indemnizatorio ofrecido por los bienes muebles e inmuebles que la firma ten\u00eda en Santa Cruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reci\u00e9n en noviembre de 2021, es decir, doce a\u00f1os despu\u00e9s de haberse decretado la expropiaci\u00f3n y desposesi\u00f3n de bienes, el Juzgado de Primera Instancia N\u00b0 2 en lo Civil, Comercial, Laboral y de Miner\u00eda de la provincia de Santa Cruz dict\u00f3 sentencia haciendo lugar a la demanda formulada por el estado santacruce\u00f1o en contra de la sociedad Antonio Barillari S.A., en virtud de la expropiaci\u00f3n del inmueble, instalaciones y bienes muebles declarados de utilidad p\u00fablica y dando por transferida la propiedad situada en la localidad de Caleta Olivia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese tribunal resolvi\u00f3 adem\u00e1s diferir la determinaci\u00f3n de la indemnizaci\u00f3n expropiatoria, declarando la nulidad del informe remitido por el Tribunal de Tasaciones de la Provincia de Santa Cruz, el que deb\u00eda proceder a su integraci\u00f3n una vez que la sentencia quede firme, con intervenci\u00f3n del representante del expropiado, emitiendo un dictamen con la tasaci\u00f3n actualizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TASACI\u00d3N DEFINITIVA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transcurrido un a\u00f1o y medio de ese fallo, a\u00fan no se ha realizado la tasaci\u00f3n definitiva y por consiguiente la determinaci\u00f3n del monto que deber\u00e1 afrontar la Provincia de Santa Cruz. Atento a que la expropiaci\u00f3n se inici\u00f3 en 2009, y han pasado m\u00e1s de trece a\u00f1os, es de prever que la cifra actualizada m\u00e1s intereses, teniendo en cuenta la inflaci\u00f3n acumulada en m\u00e1s de una d\u00e9cada, ser\u00e1 multimillonaria. Adem\u00e1s, de las instalaciones se debe dimensionar el lucro cesante, no evaluado, y gener\u00f3 un beneficio en este caso para la empresa que hoy controla la pesquera expropiada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale recordar que la firma Antonio Barillari S.A. en 2009 se encontraba atravesando un concurso preventivo de acreedores y actualmente el Juzgado Nacional de Primera Instancia en lo Comercial N\u00b0 16 de CABA, tramita la quiebra. Al tiempo que se negocia con los acreedores la venta de la sociedad en quiebra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Independientemente de ese proceso en que se encuentra la expropiada, el Estado santacruce\u00f1o deber\u00e1 asumir el pago indemnizatorio respectivo, por haberse quedado con los bienes que la pesquera ten\u00eda en el puerto de Caleta Paula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MANIOBRAS EN LAS SOMBRAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los memoriosos recuerdan que la planta procesadora que la firma Barillari pose\u00eda en Santa Cruz se expropi\u00f3 a partir de un proyecto de ley que present\u00f3, en aquel momento, el diputado oficialista Rub\u00e9n Contreras, cuando el gobernador era Daniel Peralta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien en la ley de expropiaci\u00f3n establec\u00eda que deb\u00eda conformarse un \u00f3rgano tripartito entre la provincia, el municipio y los trabajadores, el Ejecutivo Provincial dej\u00f3 en manos de un privado el manejo de la planta pesquera. Aseguran que Luis \u2018El Gringo\u2019 Jones, un hombre en aquel entonces ligado a Julio De Vido (en su m\u00e1ximo apogeo), se qued\u00f3 con el control de la f\u00e1brica. El Gobierno de Santa Cruz es el propietario de las instalaciones, las cedi\u00f3 en uso a cooperativas de trabajo, pero aseguran diferentes fuentes que quien la regentea es Vepez S.A. que es quien a la postre se benefici\u00f3 con la decisi\u00f3n gubernamental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de<\/p>\n","protected":false},"author":3,"featured_media":2506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[9],"tags":[296,297,91,298,295],"class_list":["post-2503","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-antonio-barillari","tag-caleta-olivia","tag-featured","tag-santa-cruz","tag-vepez-s-a"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nelson Saldivia\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Parte de pesca - Novedades de la pesca sin filtro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca\" \/>\n\t\t<meta property=\"og:description\" content=\"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-01T18:41:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-05T16:01:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#blogposting\",\"name\":\"Santa Cruz deber\\u00e1 pagar cifra millonaria por la expropiaci\\u00f3n de Barillari - Parte de pesca\",\"headline\":\"Santa Cruz deber\\u00e1 pagar cifra millonaria por la expropiaci\\u00f3n de Barillari\",\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg\",\"width\":1300,\"height\":783,\"caption\":\"Foto Archivo\"},\"datePublished\":\"2023-06-01T18:41:44+00:00\",\"dateModified\":\"2023-06-05T16:01:25+00:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#webpage\"},\"articleSection\":\"Actualidad, Antonio Barillari, Caleta Olivia, featured, Santa Cruz, Vepez S.A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#listItem\",\"name\":\"Santa Cruz deber\\u00e1 pagar cifra millonaria por la expropiaci\\u00f3n de Barillari\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#listItem\",\"position\":3,\"name\":\"Santa Cruz deber\\u00e1 pagar cifra millonaria por la expropiaci\\u00f3n de Barillari\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logoparte.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#organizationLogo\",\"width\":654,\"height\":402},\"image\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/\",\"name\":\"Nelson Saldivia\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/049f41f1369afed2b303aa61447f598d1d6da2db0f14f42cf82dae6e1ccffe4f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Nelson Saldivia\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#webpage\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/\",\"name\":\"Santa Cruz deber\\u00e1 pagar cifra millonaria por la expropiaci\\u00f3n de Barillari - Parte de pesca\",\"description\":\"La Legislatura de la provincia de Santa Cruz sancion\\u00f3 el 27 de octubre de 2009 la Ley N\\u00ba 3.081 en la que declar\\u00f3 de utilidad p\\u00fablica y sujeto a expropiaci\\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#mainImage\",\"width\":1300,\"height\":783,\"caption\":\"Foto Archivo\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\\\/#mainImage\"},\"datePublished\":\"2023-06-01T18:41:44+00:00\",\"dateModified\":\"2023-06-05T16:01:25+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca","description":"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de","canonical_url":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#blogposting","name":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca","headline":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari","author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg","width":1300,"height":783,"caption":"Foto Archivo"},"datePublished":"2023-06-01T18:41:44+00:00","dateModified":"2023-06-05T16:01:25+00:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#webpage"},"isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#webpage"},"articleSection":"Actualidad, Antonio Barillari, Caleta Olivia, featured, Santa Cruz, Vepez S.A"},{"@type":"BreadcrumbList","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","position":1,"name":"Home","item":"https:\/\/partedepesca.com.ar\/d","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#listItem","name":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari"},"previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#listItem","position":3,"name":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari","previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/partedepesca.com.ar\/d\/#organization","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","url":"https:\/\/partedepesca.com.ar\/d\/","logo":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/03\/logoparte.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#organizationLogo","width":654,"height":402},"image":{"@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author","url":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/","name":"Nelson Saldivia","image":{"@type":"ImageObject","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/049f41f1369afed2b303aa61447f598d1d6da2db0f14f42cf82dae6e1ccffe4f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Nelson Saldivia"}},{"@type":"WebPage","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#webpage","url":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/","name":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca","description":"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/#website"},"breadcrumb":{"@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#breadcrumblist"},"author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"creator":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#mainImage","width":1300,"height":783,"caption":"Foto Archivo"},"primaryImageOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/#mainImage"},"datePublished":"2023-06-01T18:41:44+00:00","dateModified":"2023-06-05T16:01:25+00:00"},{"@type":"WebSite","@id":"https:\/\/partedepesca.com.ar\/d\/#website","url":"https:\/\/partedepesca.com.ar\/d\/","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","inLanguage":"es-AR","publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Parte de pesca - Novedades de la pesca sin filtro","og:type":"article","og:title":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca","og:description":"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de","og:url":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/","og:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg","og:image:secure_url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg","og:image:width":1300,"og:image:height":783,"article:published_time":"2023-06-01T18:41:44+00:00","article:modified_time":"2023-06-05T16:01:25+00:00","twitter:card":"summary_large_image","twitter:title":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari - Parte de pesca","twitter:description":"La Legislatura de la provincia de Santa Cruz sancion\u00f3 el 27 de octubre de 2009 la Ley N\u00ba 3.081 en la que declar\u00f3 de utilidad p\u00fablica y sujeto a expropiaci\u00f3n el predio, instalaciones y bienes muebles que comprenden la planta de procesamiento de productos de mar de la empresa Antonio Barillari en la ciudad de","twitter:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/06\/planta-Vepez-Caleta-Olivia-ex-Barillari-1.jpg"},"aioseo_meta_data":{"post_id":"2503","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-01 18:40:30","updated":"2025-06-04 17:58:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSanta Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/partedepesca.com.ar\/d"},{"label":"Actualidad","link":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/"},{"label":"Santa Cruz deber\u00e1 pagar cifra millonaria por la expropiaci\u00f3n de Barillari","link":"https:\/\/partedepesca.com.ar\/d\/santa-cruz-debera-pagar-cifra-millonaria-por-la-expropiacion-de-barillari\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/2503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/comments?post=2503"}],"version-history":[{"count":1,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/2503\/revisions"}],"predecessor-version":[{"id":2505,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/2503\/revisions\/2505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media\/2506"}],"wp:attachment":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media?parent=2503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/categories?post=2503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags?post=2503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}