{"id":14634,"date":"2026-02-02T02:26:31","date_gmt":"2026-02-02T02:26:31","guid":{"rendered":"https:\/\/partedepesca.com.ar\/d\/?p=14634"},"modified":"2026-02-03T20:07:23","modified_gmt":"2026-02-03T20:07:23","slug":"torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca","status":"publish","type":"post","link":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/","title":{"rendered":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa de Desarrollo Pesquero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adelant\u00f3 que impulsar\u00e1 la eliminaci\u00f3n de las \u201cretenciones\u201d a las exportaciones pesqueras, si las empresas se comprometen a \u201creinvertir\u201d el ahorro fiscal, en renovaci\u00f3n de flota e infraestructura portuaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Torres acord\u00f3, hace dos semanas, con el <strong>ministro de Econom\u00eda de la Naci\u00f3n, Luis Caputo<\/strong>, un acuerdo para la eliminaci\u00f3n de las retenciones a la exportaci\u00f3n de petr\u00f3leo. En esa oportunidad, el gobernador patag\u00f3nico<strong> habr\u00eda vuelto a plantear un esquema similar para la industria pesquera <\/strong>y habr\u00eda obtenido un gui\u00f1o del titular del Palacio de Hacienda<strong>, si el sector acepta reinvertir lo que se ahorrar\u00e1 en Derechos de Exportaci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El anuncio no ser\u00eda inmediato, pero no se descarta que pueda concretarse cuando est\u00e9 iniciando la temporada de pesca de langostino en aguas nacionales,<\/strong> es decir, dentro de unos meses.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>\u201cMESA DE DESARROLLO PESQUERO\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, Torres destac\u00f3 que \u201crecientemente tuvimos la grata noticia de que en 2025 la provincia alcanz\u00f3 el mayor r\u00e9cord de exportaciones de los \u00faltimos veinte a\u00f1os, en gran medida por el crecimiento de un sector estrat\u00e9gico como la pesca, que es el que m\u00e1s empleo gener\u00f3 y el que mayor potencial tiene para seguir generando trabajo en tierra\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026-.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--1024x769.jpg\" alt=\"\" class=\"wp-image-14636\" srcset=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--1024x769.jpg 1024w, https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--300x225.jpg 300w, https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--768x577.jpg 768w, https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--150x113.jpg 150w, https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026--450x338.jpg 450w, https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/TORRES-CAPUTO-ELIMINACION-RETENCIONES-PETROLEO-18012026-.jpg 1132w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Torres y Caputo, hace dos semanas, acordaron la quita de retenciones para el petr\u00f3leo, ahora analizan eliminarlos a la pesca<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el mismo sentido, explic\u00f3 que \u201ccon el sector del petr\u00f3leo conformamos una Mesa de Competitividad en la que los gremios se comprometieron a trabajar en ese esquema, las operadoras a reinvertir el ahorro fiscal producto de la eliminaci\u00f3n de las retenciones, y la provincia hizo lo propio; y lo mismo queremos replicar en la pesca\u201d.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\"><strong>REINVERSI\u00d3N DEL AHORRO FISCAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, del cual participaron los principales representantes del sector pesquero de Chubut, \u201cplanteamos la situaci\u00f3n de las<strong> retenciones a la pesca,<\/strong> que es una de las pocas econom\u00edas regionales que no cuenta con beneficios en materia de derechos de exportaci\u00f3n\u201d, se\u00f1al\u00f3 el Gobernador, agregando que \u201clo que <strong>solicitamos es que, en la medida en que se agregue m\u00e1s valor, se reduzcan las retenciones;<\/strong> y ahora, concretamente, lo que vamos a elevar a Naci\u00f3n es una propuesta para que<strong> el ahorro fiscal producto de la eliminaci\u00f3n de los derechos de exportaci\u00f3n \u2014que oscila entre los 120 y los 160 millones de d\u00f3lares a nivel pa\u00eds\u2014 se reinvierta en renovaci\u00f3n de flota o en infraestructura portuaria\u201d<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una propuesta que beneficia a la provincia, a la generaci\u00f3n de trabajo local, al sector y tambi\u00e9n a la Naci\u00f3n, porque la falta de inversi\u00f3n en infraestructura portuaria reduce la competitividad y dificulta las exportaciones, cuando lo que Argentina hoy necesita son divisas\u201d, resalt\u00f3 el mandatario.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\"><strong>CUMBRE DE DOMINICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n dominical se desarroll\u00f3 en la Sala de Situaci\u00f3n de la Casa de Gobierno y constituy\u00f3 el primer paso para la conformaci\u00f3n de la Mesa de Desarrollo Pesquero, en el marco de la Agencia de Inversiones y Comercio Exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participaron de la reuni\u00f3n el secretario de Pesca de Chubut, <strong>Andr\u00e9s Arbeletche<\/strong>; el presidente de la C\u00e1mara de Flota Amarilla de Chubut (CAFACH), <strong>Gustavo Gonz\u00e1lez<\/strong>; el presidente de la C\u00e1mara Argentina Patag\u00f3nica de Industrias Pesqueras (CAPIP), <strong>Agust\u00edn de la Fuente<\/strong>; el titular de la C\u00e1mara de la Flota Artesanal de Puerto Rawson, <strong>Fernando Alarc\u00f3n<\/strong>; los intendentes de Puerto Madryn, <strong>Gustavo Sastre<\/strong>, y de Rawson, <strong>Dami\u00e1n Biss<\/strong>; el presidente de la Sociedad Rural del Valle del Chubut, <strong>Ricardo Iriani<\/strong>; el titular de la Agencia de Inversiones y Comercio Exterior, <strong>Jos\u00e9 Ignacio Bellorini<\/strong>; el presidente de la Agencia de Desarrollo Econ\u00f3mico de Rawson (ADER), <strong>Fernando Vosecky<\/strong>; el titular de la Federaci\u00f3n Empresaria del Chubut (FECh), <strong>Carlos Lorenzo<\/strong>; el presidente de la C\u00e1mara Industrial y de Comercio Exterior de Puerto Madryn y Regi\u00f3n Patagonia, <strong>Oscar Dethier<\/strong>; el representante de la C\u00e1mara de Industria, Comercio y Turismo de Puerto Madryn, <strong>Diego Gonz\u00e1lez Lernoud<\/strong>; y el diputado provincial <strong>Sergio Gonz\u00e1lez<\/strong>.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\"><strong>LA MILLA 201<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Torres sostuvo que \u201cno se trata solo de un problema del sector pesquero, sino de un perjuicio econ\u00f3mico que estimamos entre 600 y 1.000 millones de d\u00f3lares que el pa\u00eds pierde por temporada, producto de la depredaci\u00f3n de nuestros recursos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este marco, advirti\u00f3 que \u201ccuando hablamos de pesca ilegal, tambi\u00e9n hablamos de otros delitos complejos, como la trata de personas; es una problem\u00e1tica que se arrastra desde hace d\u00e9cadas y que requiere una respuesta integral\u201d, y explic\u00f3 que existe un proyecto de ley que contempla \u201cla figura del Estado rector del puerto, para garantizar la trazabilidad de quienes hacen las cosas bien -pagan impuestos y tienen a sus trabajadores en blanco- y diferenciar a quienes act\u00faan por fuera de la ley\u201d.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\"><strong>LLAMADO AL CANCILLER QUIRNO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una discusi\u00f3n que tenemos que dar con firmeza, porque hay una cuesti\u00f3n de soberan\u00eda que implica defender lo nuestro. Hoy nos est\u00e1n robando recursos por hasta 1.000 millones de d\u00f3lares por temporada, y Chubut es la provincia m\u00e1s perjudicada porque la Milla 201 se encuentra frente a nuestras costas e impacta directamente en la jurisdicci\u00f3n de las aguas provinciales\u201d, se\u00f1al\u00f3 Torres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el Gobernador confirm\u00f3 que este lunes se contactar\u00e1 con el ministro de Relaciones Exteriores de la Naci\u00f3n, Pablo Quirno, \u201cpara retomar una agenda que consideramos fundamental en materia econ\u00f3mica y de soberan\u00eda\u201d, y remarc\u00f3 que \u201cnecesitamos actuar con urgencia, porque cada a\u00f1o la cantidad de poteros ilegales crece exponencialmente y el da\u00f1o que sufre el pa\u00eds es cada vez mayor\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa<\/p>\n","protected":false},"author":3,"featured_media":14635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[6],"tags":[410,194,618,91,235,172,1734,4,678],"class_list":["post-14634","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comercio-exterior","tag-cafach","tag-capip","tag-derechos-de-exportacion","tag-featured","tag-ignacio-torres","tag-industria-pesquera","tag-luis-caputo","tag-pesca","tag-retenciones"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nelson Saldivia\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Parte de pesca - Novedades de la pesca sin filtro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca\" \/>\n\t\t<meta property=\"og:description\" content=\"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1551\" \/>\n\t\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-02-02T02:26:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-03T20:07:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#blogposting\",\"name\":\"Torres tendr\\u00eda el gui\\u00f1o de \\u2018Toto\\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca\",\"headline\":\"Torres tendr\\u00eda el gui\\u00f1o de \\u2018Toto\\u2019 Caputo para la quita de retenciones a la pesca\",\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/torres-capip-cafach-retenciones-milla-201-2.jpeg\",\"width\":1551,\"height\":776},\"datePublished\":\"2026-02-02T02:26:31+00:00\",\"dateModified\":\"2026-02-03T20:07:23+00:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#webpage\"},\"articleSection\":\"Comercio Exterior, CAFACH, capip, derechos de exportacion, featured, Ignacio Torres, industria pesquera, Luis Caputo, pesca, retenciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/comercio-exterior\\\/#listItem\",\"name\":\"Comercio Exterior\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/comercio-exterior\\\/#listItem\",\"position\":2,\"name\":\"Comercio Exterior\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/comercio-exterior\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#listItem\",\"name\":\"Torres tendr\\u00eda el gui\\u00f1o de \\u2018Toto\\u2019 Caputo para la quita de retenciones a la pesca\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#listItem\",\"position\":3,\"name\":\"Torres tendr\\u00eda el gui\\u00f1o de \\u2018Toto\\u2019 Caputo para la quita de retenciones a la pesca\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/comercio-exterior\\\/#listItem\",\"name\":\"Comercio Exterior\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logoparte.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#organizationLogo\",\"width\":654,\"height\":402},\"image\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/\",\"name\":\"Nelson Saldivia\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/049f41f1369afed2b303aa61447f598d1d6da2db0f14f42cf82dae6e1ccffe4f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Nelson Saldivia\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#webpage\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/\",\"name\":\"Torres tendr\\u00eda el gui\\u00f1o de \\u2018Toto\\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca\",\"description\":\"El gobernador del Chubut, Ignacio Torres, encabez\\u00f3 este domingo una reuni\\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\\u00f3 en el petr\\u00f3leo con la conformaci\\u00f3n de la una Mesa\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/nelsons\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/torres-capip-cafach-retenciones-milla-201-2.jpeg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#mainImage\",\"width\":1551,\"height\":776},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\\\/#mainImage\"},\"datePublished\":\"2026-02-02T02:26:31+00:00\",\"dateModified\":\"2026-02-03T20:07:23+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca","description":"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa","canonical_url":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#blogposting","name":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca","headline":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca","author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg","width":1551,"height":776},"datePublished":"2026-02-02T02:26:31+00:00","dateModified":"2026-02-03T20:07:23+00:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#webpage"},"isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#webpage"},"articleSection":"Comercio Exterior, CAFACH, capip, derechos de exportacion, featured, Ignacio Torres, industria pesquera, Luis Caputo, pesca, retenciones"},{"@type":"BreadcrumbList","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","position":1,"name":"Home","item":"https:\/\/partedepesca.com.ar\/d","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/#listItem","name":"Comercio Exterior"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/#listItem","position":2,"name":"Comercio Exterior","item":"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#listItem","name":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca"},"previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#listItem","position":3,"name":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca","previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/#listItem","name":"Comercio Exterior"}}]},{"@type":"Organization","@id":"https:\/\/partedepesca.com.ar\/d\/#organization","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","url":"https:\/\/partedepesca.com.ar\/d\/","logo":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/03\/logoparte.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#organizationLogo","width":654,"height":402},"image":{"@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author","url":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/","name":"Nelson Saldivia","image":{"@type":"ImageObject","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/049f41f1369afed2b303aa61447f598d1d6da2db0f14f42cf82dae6e1ccffe4f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Nelson Saldivia"}},{"@type":"WebPage","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#webpage","url":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/","name":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca","description":"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/#website"},"breadcrumb":{"@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#breadcrumblist"},"author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"creator":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/nelsons\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg","@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#mainImage","width":1551,"height":776},"primaryImageOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/#mainImage"},"datePublished":"2026-02-02T02:26:31+00:00","dateModified":"2026-02-03T20:07:23+00:00"},{"@type":"WebSite","@id":"https:\/\/partedepesca.com.ar\/d\/#website","url":"https:\/\/partedepesca.com.ar\/d\/","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","inLanguage":"es-AR","publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Parte de pesca - Novedades de la pesca sin filtro","og:type":"article","og:title":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca","og:description":"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa","og:url":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/","og:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg","og:image:secure_url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg","og:image:width":1551,"og:image:height":776,"article:published_time":"2026-02-02T02:26:31+00:00","article:modified_time":"2026-02-03T20:07:23+00:00","twitter:card":"summary_large_image","twitter:title":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca - Parte de pesca","twitter:description":"El gobernador del Chubut, Ignacio Torres, encabez\u00f3 este domingo una reuni\u00f3n con representantes de la industria pesquera en la que se abordaron cuestiones vinculadas a los Derechos de Exportaci\u00f3n que pesa sobre la actividad. El mandatario busca replicar en la pesca el esquema que instrument\u00f3 en el petr\u00f3leo con la conformaci\u00f3n de la una Mesa","twitter:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2026\/02\/torres-capip-cafach-retenciones-milla-201-2.jpeg"},"aioseo_meta_data":{"post_id":"14634","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-02-02 02:26:32","updated":"2026-02-03 20:07:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/\" title=\"Comercio Exterior\">Comercio Exterior<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTorres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/partedepesca.com.ar\/d"},{"label":"Comercio Exterior","link":"https:\/\/partedepesca.com.ar\/d\/temas\/comercio-exterior\/"},{"label":"Torres tendr\u00eda el gui\u00f1o de \u2018Toto\u2019 Caputo para la quita de retenciones a la pesca","link":"https:\/\/partedepesca.com.ar\/d\/torres-tendria-el-guino-de-toto-caputo-para-la-quita-de-retenciones-a-la-pesca\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/14634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/comments?post=14634"}],"version-history":[{"count":2,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/14634\/revisions"}],"predecessor-version":[{"id":14638,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/14634\/revisions\/14638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media\/14635"}],"wp:attachment":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media?parent=14634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/categories?post=14634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags?post=14634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}