{"id":11928,"date":"2025-05-12T08:33:00","date_gmt":"2025-05-12T08:33:00","guid":{"rendered":"https:\/\/partedepesca.com.ar\/d\/?p=11928"},"modified":"2025-05-12T11:22:50","modified_gmt":"2025-05-12T11:22:50","slug":"ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir","status":"publish","type":"post","link":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/","title":{"rendered":"Ante la indiferencia sindical, marinero pide ayuda para no morir"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la obra social le prometieron ayuda, pero finalmente no hubo contacto y el trabajador de mar se ve obligado a volver a pedir la solidaridad de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las recomendaciones m\u00e9dicas recibidas, D\u00edaz cont\u00f3 en un video divulgado en redes sociales, que debe aplicarse seis ampollas de un determinado medicamento, pero la obra social del SOMU le niega su cobertura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esta circunstancia, Mauro D\u00edaz, revel\u00f3 que esas ampollas tienen un costo de tres ciento cincuenta mil pesos ($350.000), cada una, las que hoy no est\u00e1n a su alcance, por lo que pide ayuda para poder comprarlas y aplic\u00e1rselas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoce que su situaci\u00f3n sigue siendo desesperante, sin contar con la asistencia de la organizaci\u00f3n sindical a la que pertenece, pero hizo especial agradecimiento a toda la comunidad mar\u00edtimas que s\u00ed lo ha ayudado y acompa\u00f1ado en este duro proceso.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"marinero pide ayuda para no morir\" width=\"788\" height=\"443\" src=\"https:\/\/www.youtube.com\/embed\/Ys-KY5d5Lyw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra<\/p>\n","protected":false},"author":4,"featured_media":11929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[91,2131,2100,2096,179],"class_list":["post-11928","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-featured","tag-marinero","tag-mauro-diaz","tag-obra-social","tag-somu"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"redaccion\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Parte de pesca - Novedades de la pesca sin filtro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca\" \/>\n\t\t<meta property=\"og:description\" content=\"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1276\" \/>\n\t\t<meta property=\"og:image:height\" content=\"847\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-12T08:33:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-12T11:22:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#blogposting\",\"name\":\"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca\",\"headline\":\"Ante la indiferencia sindical, marinero pide ayuda para no morir\",\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/mauro-diaz-marinero-pide-ayuda.jpg\",\"width\":1276,\"height\":847},\"datePublished\":\"2025-05-12T08:33:00+00:00\",\"dateModified\":\"2025-05-12T11:22:50+00:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#webpage\"},\"articleSection\":\"Actualidad, featured, marinero, Mauro D\\u00edaz, obra social, somu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#listItem\",\"name\":\"Ante la indiferencia sindical, marinero pide ayuda para no morir\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#listItem\",\"position\":3,\"name\":\"Ante la indiferencia sindical, marinero pide ayuda para no morir\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/temas\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logoparte.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#organizationLogo\",\"width\":654,\"height\":402},\"image\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/redaccion\\\/\",\"name\":\"redaccion\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/573f0a5081c0a61fd6ac39287b5e137712bd2c79944a96eca6e6fe1474d00d0a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"redaccion\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#webpage\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/\",\"name\":\"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca\",\"description\":\"Mauro D\\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\\u00f3gico no han tenido eco en el seno de la organizaci\\u00f3n sindical. Desde la obra\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/mauro-diaz-marinero-pide-ayuda.jpg\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#mainImage\",\"width\":1276,\"height\":847},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\\\/#mainImage\"},\"datePublished\":\"2025-05-12T08:33:00+00:00\",\"dateModified\":\"2025-05-12T11:22:50+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#website\",\"url\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/\",\"name\":\"Parte de pesca\",\"description\":\"Novedades de la pesca sin filtro\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/partedepesca.com.ar\\\/d\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca","description":"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra","canonical_url":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#blogposting","name":"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca","headline":"Ante la indiferencia sindical, marinero pide ayuda para no morir","author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg","width":1276,"height":847},"datePublished":"2025-05-12T08:33:00+00:00","dateModified":"2025-05-12T11:22:50+00:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#webpage"},"isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#webpage"},"articleSection":"Actualidad, featured, marinero, Mauro D\u00edaz, obra social, somu"},{"@type":"BreadcrumbList","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","position":1,"name":"Home","item":"https:\/\/partedepesca.com.ar\/d","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#listItem","name":"Ante la indiferencia sindical, marinero pide ayuda para no morir"},"previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#listItem","position":3,"name":"Ante la indiferencia sindical, marinero pide ayuda para no morir","previousItem":{"@type":"ListItem","@id":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/partedepesca.com.ar\/d\/#organization","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","url":"https:\/\/partedepesca.com.ar\/d\/","logo":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2023\/03\/logoparte.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#organizationLogo","width":654,"height":402},"image":{"@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/partedepesca.com.ar\/d\/author\/redaccion\/#author","url":"https:\/\/partedepesca.com.ar\/d\/author\/redaccion\/","name":"redaccion","image":{"@type":"ImageObject","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/573f0a5081c0a61fd6ac39287b5e137712bd2c79944a96eca6e6fe1474d00d0a?s=96&d=mm&r=g","width":96,"height":96,"caption":"redaccion"}},{"@type":"WebPage","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#webpage","url":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/","name":"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca","description":"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/partedepesca.com.ar\/d\/#website"},"breadcrumb":{"@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#breadcrumblist"},"author":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/partedepesca.com.ar\/d\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg","@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#mainImage","width":1276,"height":847},"primaryImageOfPage":{"@id":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/#mainImage"},"datePublished":"2025-05-12T08:33:00+00:00","dateModified":"2025-05-12T11:22:50+00:00"},{"@type":"WebSite","@id":"https:\/\/partedepesca.com.ar\/d\/#website","url":"https:\/\/partedepesca.com.ar\/d\/","name":"Parte de pesca","description":"Novedades de la pesca sin filtro","inLanguage":"es-AR","publisher":{"@id":"https:\/\/partedepesca.com.ar\/d\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Parte de pesca - Novedades de la pesca sin filtro","og:type":"article","og:title":"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca","og:description":"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra","og:url":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/","og:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg","og:image:secure_url":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg","og:image:width":1276,"og:image:height":847,"article:published_time":"2025-05-12T08:33:00+00:00","article:modified_time":"2025-05-12T11:22:50+00:00","twitter:card":"summary_large_image","twitter:title":"Ante la indiferencia sindical, marinero pide ayuda para no morir - Parte de pesca","twitter:description":"Mauro D\u00edaz es el marinero de Rawson que fue abandonado por el SOMU en medio de una cruel enfermedad que atraviesa. Sus incesantes reclamos ante el sindicato para que se haga cargo de los altos costos que genera el tratamiento oncol\u00f3gico no han tenido eco en el seno de la organizaci\u00f3n sindical. Desde la obra","twitter:image":"https:\/\/partedepesca.com.ar\/d\/wp-content\/uploads\/2025\/05\/mauro-diaz-marinero-pide-ayuda.jpg"},"aioseo_meta_data":{"post_id":"11928","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-05-12 11:19:01","updated":"2025-06-04 20:50:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAnte la indiferencia sindical, marinero pide ayuda para no morir\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/partedepesca.com.ar\/d"},{"label":"Actualidad","link":"https:\/\/partedepesca.com.ar\/d\/temas\/actualidad\/"},{"label":"Ante la indiferencia sindical, marinero pide ayuda para no morir","link":"https:\/\/partedepesca.com.ar\/d\/ante-la-indiferencia-sindical-marinero-pide-ayuda-para-no-morir\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/11928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/comments?post=11928"}],"version-history":[{"count":2,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/11928\/revisions"}],"predecessor-version":[{"id":11931,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/posts\/11928\/revisions\/11931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media\/11929"}],"wp:attachment":[{"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/media?parent=11928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/categories?post=11928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/partedepesca.com.ar\/d\/wp-json\/wp\/v2\/tags?post=11928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}